{"id":2050,"date":"2016-03-08T11:40:14","date_gmt":"2016-03-08T10:40:14","guid":{"rendered":"https:\/\/www.herole.de\/blog\/?p=2050"},"modified":"2024-10-04T11:10:18","modified_gmt":"2024-10-04T09:10:18","slug":"unterrichtsthema-flucht-asyl-migration-praxis-tipps","status":"publish","type":"post","link":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/","title":{"rendered":"Flucht und Asyl als Unterrichtsthema &#8211; Tipps"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2050\" class=\"elementor elementor-2050\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-366444eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"366444eb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-730bbf88\" data-id=\"730bbf88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24388764 elementor-widget elementor-widget-text-editor\" data-id=\"24388764\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gerade f\u00fcr Lehrer kann es eine gro\u00dfe Herausforderung sein, geeignete Wege der Vermittlung zu finden, denn eine Lerneinheit zu diesem Thema sollte nicht nur vorurteilsfrei Wissen vermitteln, sondern die Sch\u00fcler auch zur eigenen Auseinandersetzung anregen. Auf der Basis der Handreichung <i class=\"svg-icon-doc\"><\/i><a href=\"#linksammlung\" target=\"_blank\" rel=\"noopener\">\u201eFlucht &amp; Asyl: Ein Thema im Klassenzimmer\u201c<\/a>\u00a0des\u00a0<a href=\"#linksammlung\" target=\"_blank\" rel=\"noopener\">S\u00e4chsischen Fl\u00fcchtlingsrats<\/a> und anderer\u00a0<a href=\"#linksammlung\" target=\"_blank\" rel=\"noopener\">Bildungsseiten<\/a>\u00a0geben wir einige Ratschl\u00e4ge, wie das Thema \u201eFlucht, Asyl, Migration\u201c in der Schulpraxis behandelt werden kann.<\/p><h2><span id=\"Sich_Wissen_aneignen\">Sich Wissen aneignen<\/span><\/h2><p>Alle Lehrer wissen: Die Basis f\u00fcr jegliche Art der Unterrichtsvorbereitung ist es, sich Informationen anzueignen, um selbst f\u00fcr ein Thema sensibilisiert zu sein und eventuelle R\u00fcckfragen beantworten zu k\u00f6nnen. Auch beim Fokus \u201eFlucht, Asyl, Migration\u201c ist es entscheidend, dass sich Lehrer im Vorfeld gr\u00fcndlich informieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c5cbd4 elementor-blockquote--skin-clean elementor-blockquote--button-color-official elementor-widget elementor-widget-blockquote\" data-id=\"4c5cbd4\" data-element_type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\u201eWissen bedeutet, ein Thema kompetent vermitteln, sich mit unterschiedlichen Positionen auseinandersetzen und Vorurteilen, die meist auf Unwissenheit beruhen, entgegnen zu k\u00f6nnen.\u201c\n\u2013 Handreichung \u201eFlucht & Asyl: Ein Thema im Klassenzimmer\u201c, S\u00e4chsischer Fl\u00fcchtlingsrat e.V.\t\t\t<\/p>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13b6ac0 elementor-widget elementor-widget-text-editor\" data-id=\"13b6ac0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In der Handreichung \u201eFlucht &amp; Asyl: Ein Thema im Klassenzimmer\u201c wird Lehrern zus\u00e4tzlich die <strong>Teilnahme an Workshops oder Weiterbildungen <\/strong>empfohlen, bevor sie das Thema mit Eltern und Sch\u00fclern besprechen.<\/p><p>Da viele Lehrer selbst keine Experten f\u00fcr das Thema sind, kann als erg\u00e4nzende Ma\u00dfnahme auch erw\u00e4gt werden, <strong>Multiplikatoren der au\u00dferschulischen Bildungsarbeit<\/strong> einzuladen, die das Thema einf\u00fchren, von ihrer Erfahrung erz\u00e4hlen und eine Diskussion im Klassenzimmer anleiten k\u00f6nnen; die Arbeit wird sp\u00e4ter im Unterricht fortgesetzt, mit den Sch\u00fclern k\u00f6nnen dann beispielsweise Handlungsm\u00f6glichkeiten erarbeitet und gemeinsame Aktionen geplant werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b59dca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b59dca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2af2d55 auto-width\" data-id=\"2af2d55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68e0e96 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"68e0e96\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-blog_tip\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-803d506\" data-id=\"803d506\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6478ffe tip elementor-widget elementor-widget-text-editor\" data-id=\"6478ffe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im ersten Teil der Serie \u201eUnterrichtsthema \u201eFlucht, Asyl, Migration\u201c listen wir Websites und Publikationen auf, die Lehrern dabei helfen sollen, sich auf den Unterricht vorzubereiten. Mehr Informationen gibt es <a href=\"https:\/\/www.herole.de\/blog\/lehrertipps\/politisches\/\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc9cc40 elementor-widget elementor-widget-text-editor\" data-id=\"fc9cc40\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span id=\"Unterrichtsziele_definieren\">Unterrichtsziele definieren<\/span><\/h2><p>Die Ziele der Auseinandersetzung mit den Themen \u201eFlucht, Asyl, Migration\u201c\u00a0im Unterricht m\u00fcssen klar definiert sein. Laut der Handreichung \u201eFlucht &amp; Asyl: Ein Thema im Klassenzimmer\u201c sollte die Auseinandersetzung folgende<strong> drei Schritte<\/strong> umfassen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45702fb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"45702fb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-ok\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Erzeugung eines Perspektivwechsels<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-ok\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wissensvermittlung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-ok\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aufzeigen von Handlungsm\u00f6glichkeiten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17700b94 elementor-widget elementor-widget-text-editor\" data-id=\"17700b94\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Perspektivwechsel erzeugen<\/h3><p>Mit &#8222;Perspektivwechsel&#8220; ist die F\u00f6rderung von Verst\u00e4ndnis daf\u00fcr gemeint, welche Gr\u00fcnde Menschen zur Flucht und Migration bewegen. Hier k\u00f6nnen Hintergr\u00fcnde, Ursachen oder der Fluchtweg aufgezeigt werden, aber auch die Situation, in der sich gefl\u00fcchtete Menschen in Deutschland oder Europa befinden. Das Unterrichtsziel sollte hier sein, dass die Sch\u00fcler andere Lebensgeschichten erfahren und lernen, sich in sie hineinzuversetzen. Ihre F\u00e4higkeit, <strong>Empathie<\/strong> <strong>zu entwickeln<\/strong>, wird gef\u00f6rdert.<\/p><h3>Wissen vermitteln<\/h3><p>Wissen erm\u00f6glicht den Sch\u00fclern, sich konstruktiv und neugierig mit anderen Menschen und Sachverhalten auseinanderzusetzen. In diesem Schritt werden die durch den Perspektivwechsel gemachten Erfahrungen in einen Kontext gesetzt, vertieft und reflektiert. Ein weiteres Ziel der Wissensvermittlung kann auch sein, <strong>Vorurteile abzubauen <\/strong>oder auf die Vorurteile anderer entsprechend reagieren zu k\u00f6nnen.<\/p><h3>Handlungsm\u00f6glichkeiten aufzeigen<\/h3><p>Nach dieser eher theoretischen Einf\u00fchrung in das Thema, soll ein dritter Schritt die Sch\u00fcler dazu anregen, aktiv zu werden. Die Sch\u00fcler sollen lernen, dass sie in einer demokratischen Gesellschaft selbst<strong> Einfluss nehmen<\/strong> k\u00f6nnen und in der Schule und in ihrem pers\u00f6nlichen Alltag handelnd mit Themen umgehen k\u00f6nnen.<\/p><h2>Methoden w\u00e4hlen<\/h2><p>Sind die Ziele der Unterrichtseinheiten erst einmal gesetzt, ist es oft leichter, den richtigen Vermittlungsansatz zu w\u00e4hlen. Die Methoden f\u00fcr die drei vorgeschlagenen Schritte sind nicht immer klar voneinander zu trennen. Sie unterscheiden sich jedoch hinsichtlich des Aktivit\u00e4tsgrads, der von den Sch\u00fclern gefordert wird.<\/p><h3>Perspektivwechsel erzeugen<\/h3><p>F\u00fcr das Unterrichtsziel &#8222;Perspektivwechsel erzeugen&#8220; werden in der Handreichung \u201eFlucht &amp; Asyl: Ein Thema im Klassenzimmer\u201c verschiedene Wege vorgeschlagen, die bei den Sch\u00fclern Empathie erzeugen k\u00f6nnen:<\/p><p>Ein Ansatz sind<strong> handlungsorientierte \u00dcbungen: <\/strong>Indem ein 6m\u00b2 Wohnfl\u00e4che auf dem Fu\u00dfboden abgeklebt wird und nun fiktiv eingerichtet werden soll, setzen die Sch\u00fcler sich implizit mit der Lebenssituation von Asylsuchenden auseinander. Auch wenn die Sch\u00fcler dar\u00fcber reflektieren, aus welchen Gr\u00fcnden sie selbst migrieren oder fl\u00fcchten w\u00fcrden, f\u00fchrt das oft zu einem Perspektivwechsel.<\/p><p>Eine andere M\u00f6glichkeit ist der Einsatz von <strong>Literatur<\/strong>, welche die Perspektive von gefl\u00fcchteten oder migrierten Menschen widerspiegelt. Ebenso anschaulich ist die Arbeit mit <strong>Dokumentar-, Spiel- oder Animationsfilmen<\/strong> zum Thema oder der <strong>Besuch eines Theaterst\u00fcckes oder einer Ausstellung<\/strong> mit anschlie\u00dfendem Gespr\u00e4ch dar\u00fcber.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e55d381 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e55d381\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-89c97fe auto-width\" data-id=\"89c97fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad9a801 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ad9a801\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-blog_tip\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1189abf\" data-id=\"1189abf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f74c7e0 tip elementor-widget elementor-widget-text-editor\" data-id=\"f74c7e0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Am Ende des Artikels haben wir einige Vorschl\u00e4ge f\u00fcr die Arbeit mit B\u00fcchern, Filmen, Theaterst\u00fccken und Ausstellungen aufgelistet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-68c641e elementor-widget elementor-widget-text-editor\" data-id=\"68c641e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der direkteste Zugang, sich mit der Lebenserfahrung anderer Menschen auseinanderzusetzen, ist freilich eine <strong>Gespr\u00e4chsrunde oder eine andere Begegnungsm\u00f6glichkeit mit gefl\u00fcchteten oder migrierten Menschen.<\/strong> Bei der Moderation eines solchen Gespr\u00e4chs ist darauf zu achten, dass der eingeladene Gast gleichberechtigt behandelt wird und sich nicht \u201evorgef\u00fchrt\u201c f\u00fchlt.<\/p><h3><span id=\"Wissen_vermitteln-2\">Wissen vermitteln<\/span><\/h3><p>Der Themenkomplex \u201eFlucht, Migration, Asyl\u201c ist sehr gro\u00df. Daher bietet es sich an, den Fokus zun\u00e4chst auf bestimmte Fragestellungen zu legen und diese vertiefend zu beleuchten, um das Allgemeine anhand des Speziellen zu erz\u00e4hlen. Auch ein\u00a0<strong>Stationenlernen<\/strong> ist bei dem Thema denkbar. Fragen, die auftauchen k\u00f6nnen, sind beispielsweise:<\/p><ul><li>Was ist ein \u201eFl\u00fcchtling\u201c?\u00a0Was ist der Unterschied zwischen Flucht und Migration?<\/li><li>Warum und wovor fliehen Menschen?<\/li><li>Wann und warum sind in der Vergangenheit Menschen aus Deutschland geflohen?<\/li><li>Welche\u00a0weltweiten Fluchtbewegungen gibt es und in welchem Verh\u00e4ltnis stehen sie zu den Asylantr\u00e4gen in Deutschland oder Europa?<\/li><li>Wo und wie leben gefl\u00fcchtete Menschen in Deutschland oder Europa? Wie d\u00fcrfen sie sich bewegen?<\/li><li>Was ist ein \u201eAsylbewerber\u201c?<\/li><li>Wie hat sich das Grundrecht auf Asyl entwickelt?<\/li><li>Wie wird mit Migrationsbewegungen auf der Ebene der BRD oder EU politisch verfahren?<\/li><\/ul><p>In diesem Schritt bietet es sich an, mit informationsbasierter <strong>Literatur<\/strong>, <strong>Publikationen, Reportagen<\/strong> oder <strong>Dokumentationen<\/strong> zu arbeiten. Auch ein <strong>Workshop<\/strong> mit einem externen Experten, z.B. einem Fl\u00fcchtlingsrat, ist denkbar. Ein\u00a0<strong>Argumentationstraining<\/strong> bef\u00e4higt die Sch\u00fcler dazu, Vorurteilen sachlich und fundiert begegnen zu k\u00f6nnen.<\/p><h3><span id=\"Handlungsmoeglichkeiten_aufzeigen-2\">Handlungsm\u00f6glichkeiten aufzeigen<\/span><\/h3><p>Besonders sch\u00f6n sind <strong>Begegnungsprojekte<\/strong>, in denen alle Beteiligten <strong>auf Augenh\u00f6he<\/strong> zusammen etwas umsetzen: Das kann z.B. gemeinsames Kochen oder Musizieren mit Gefl\u00fcchteten sein, Asylsuchende k\u00f6nnen gebeten werden, eine Unterrichtseinheit zu gestalten (z.B. zu ihrer Herkunftsregion) oder die Sch\u00fcler k\u00f6nnen Sprachtandems oder Bildungspartnerschaften \u00fcbernehmen. Auch thematische Aktionen zum Schulfest oder Projekttag sind denkbar, z.B. eine Spendensammelaktion, ein Filmdreh oder ein Infostand. Aber auch eine <a href=\"https:\/\/www.herole.de\/klassenfahrten\">Klassenfahrt<\/a> kann dabei helfen unterschiedliche Kulturen einander n\u00e4her zu bringen.<\/p><p>Die Projektideen sollten <strong>gemeinsam mit den Sch\u00fclern<\/strong> entwickelt werden, denn nur wenn die Sch\u00fcler sich in der Aktion wiedererkennen, werden sie bestenfalls motiviert sein, auch \u00fcber ihren Schulalltag hinaus aktiv zu werden. Mit Hilfe der unten stehenden Materialliste soll ein Ansto\u00df f\u00fcr solche Ideen gegeben werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a2e8f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a2e8f5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-60f799b auto-width\" data-id=\"60f799b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d705991 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d705991\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-blog_tip\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-55bf2ee\" data-id=\"55bf2ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27ee9e0 tip elementor-widget elementor-widget-text-editor\" data-id=\"27ee9e0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alle\u00a0Artikel zum Unterrichtsthema &#8222;Flucht, Asyl, Migration&#8220; mit n\u00fctzlichen Hinweisen, Links und Materialien finden sich\u00a0<a href=\"https:\/\/www.herole.de\/blog\/lehrertipps\/politisches\/\" target=\"_blank\" rel=\"noopener\">hier<\/a>\u00a0als \u00dcberblick.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b098111 elementor-cta--valign-top lines lines-1 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"b098111\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tMehr Erfahren\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tZur Inspiration f\u00fcr eigene Aktionen haben wir einige Schulprojekte und Wettbewerbe rund um das Thema \u201eFlucht, Asyl, Migration\u201c zusammengetragen.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-aktionen\/\">\n\t\t\t\t\t\tWeiterlesen \t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab4e9cf elementor-widget elementor-widget-button\" data-id=\"ab4e9cf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.herole.de\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr \u00fcber HEROLE erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49ff31dc elementor-widget elementor-widget-menu-anchor\" data-id=\"49ff31dc\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"linksammlung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55083a6c elementor-widget elementor-widget-text-editor\" data-id=\"55083a6c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Linksammlung<\/h2><h3>Quellen<\/h3><ul><li>Handreichung: <a href=\"https:\/\/www.frsh.de\/fileadmin\/beiboot\/BB17\/BB-17-16-Anlage.pdf\">&#8222;Flucht &amp; Asyl: Ein Thema im Klassenzimmer&#8220;<\/a><\/li><li>S\u00e4chsischer Fl\u00fcchtlinksrat: <a href=\"http:\/\/www.saechsischer-fluechtlingsrat.de\/de\/\">Website<\/a><\/li><li>bildungsserver.de: <a href=\"https:\/\/www.bildungsserver.de\/Flucht-Asyl-und-Migration-3377-de.html\">Website<\/a><\/li><\/ul><h3>Materialien<\/h3><p><strong>Unterrichtseinheiten<\/strong><\/p><ul><li>Arbeitsbl\u00e4tter und Unterrichtsentw\u00fcrfe zum Thema &#8222;Flucht&#8220;, &#8222;Asyl&#8220;, &#8222;Migration&#8220; und &#8222;Vertreibung&#8220;: <a href=\"https:\/\/digital.zlb.de\/viewer\/metadata\/15967484\/1\/\" target=\"_blank\" rel=\"noopener\">Handreichung &#8222;Lernen \u00fcber Migration und Menschenrechte: Fl\u00fcchtlinge gestern \u2013 Fl\u00fcchtlinge heute<\/a>&#8222;<\/li><li>Zw\u00f6lf Lernstationen f\u00fcr Sch\u00fcler ab Klasse 7 zum kostenfreien Download: <a href=\"https:\/\/www.kkstiftung.de\/de\/themen\/bildung\/globales-lernen\/arbeitspaket-zu-den-themen-flucht-und-migration.htm\" target=\"_blank\" rel=\"noopener\">Arbeitspaket &#8222;Fl\u00fcchtlinge&#8220; der Karl K\u00fcbel Stiftung<\/a><\/li><li>Sieben bis acht Schulstunden f\u00fcr Sch\u00fcler ab Klasse 8 mit kostenfreiem Material: <a href=\"https:\/\/www.proasyl.de\/material\/\" target=\"_blank\" rel=\"noopener\">Unterrichtseinheit &#8222;Fl\u00fcchtlinge &#8211; und wie Deutschland mit ihnen umgeht&#8220; bei lehrer-online.de<\/a><\/li><li>Informations- und Unterrichtsmaterialien f\u00fcr Sch\u00fcler ab Klasse 9 zum kostenfreien Download: <a href=\"https:\/\/www.unhcr.org\/dach\/wp-content\/uploads\/sites\/27\/2017\/03\/Flucht-und-Asyl-1.pdf\" target=\"_blank\" rel=\"noopener\">Lehrmaterial &#8222;Flucht und Asyl&#8220; der UNHCR<\/a><\/li><\/ul><p><strong>Literatur \/ Graphic Novels<\/strong><\/p><ul><li>Abirached, Zeina: &#8222;Ich erinnere mich&#8220;, Berlin, 2014.<\/li><li>Bulling, Paula: &#8222;Im Land der Fr\u00fchaufsteher&#8220;, Berlin, 2012.<\/li><li>Neyestani, Mana: &#8222;Ein iranischer Albtraum&#8220;, Z\u00fcrich, 2013.<\/li><li>Oulios, Miltiadis: &#8222;Blackbox Abschiebung. Geschichten und Bilder von Leuten, die gerne geblieben w\u00e4ren&#8220;, Berlin, 2013.<\/li><li>Tiet\u00e4v\u00e4inen, Ville: &#8222;Unsichtbare H\u00e4nde&#8220;, Berlin, 2014.<\/li><\/ul><p><strong>Filme \/ Videos \/ Dokumentationen \/ Reportagen<\/strong><\/p><ul><li>Arnold, Loretta; Schneider, Andrea; Friedli, Fabio; Portmann, Mario: &#8222;Heimatland&#8220; (Animationsfilm, 7 Min., ab 12 Jahren, auf der DVD \u201eanderswo daheim\u201c)<\/li><li>H\u00e4nsel, Marion: &#8222;Als der Wind den Sand ber\u00fchrte&#8220; (Spielfilm, 92 Min., ab 12 Jahren)<\/li><li>Kusturica, Nina: &#8222;Little Alien&#8220; (Dokumentarfilm, 94 Min., ohne Altersbeschr\u00e4nkung)<\/li><li>Oelkers, Julia; Maibaum, Lars:&#8220;Can&#8217;t be silent&#8220; (Dokumentarfilm, 85 Min., ohne Altersbeschr\u00e4nkung, mit Unterrichtsmaterial)<\/li><li>Rau, Carsten; Wendler, Hauke: &#8222;Wadim&#8220; (Dokumentarfilm, 90 Min., ab 12 Jahre)<\/li><li>Riahi, Arash T.: &#8222;Ein Augenblick Freiheit \u2013 For a Moment Freedom&#8220; (Spielfilm, 110 Min., ab 14 Jahren)<\/li><li>&#8222;Seeking Refuge&#8220; (&#8222;Zuflucht gesucht&#8220;) (Kurzfilme, f\u00fcr Grundsch\u00fcler, mit kostenlosem Unterrichtsmaterial)<\/li><li>Tour\u00e9, Moussa: &#8222;Die Piroge&#8220; (Spielfilm, 87 Min., ab 12 Jahren)<\/li><li>sofatutor.com: <a href=\"https:\/\/www.sofatutor.com\/sachunterricht\/medien-und-kultur\/andere-kulturen\" target=\"_blank\" rel=\"noopener\">&#8222;Willi und die Entwicklungshilfe \u2013 Menschen im Fl\u00fcchtlingslager&#8220;<\/a><\/li><li>proasyl.de: <a href=\"https:\/\/www.proasyl.de\/material\/\" target=\"_blank\" rel=\"noopener\">Verschiedene Videos zum Thema &#8222;Flucht&#8220;<\/a><\/li><\/ul><h3>Ausstellungen \/ Theater<\/h3><ul><li>Wanderausstellung \u00fcber Menschen in Dresden und Umgebung, die in Asylsuchendenheimen leben: <a href=\"http:\/\/www.eingeschlossen-ausgeschlossen.de\/\" target=\"_blank\" rel=\"noopener\">\u201eEingeschlossen: Ausgeschlossen \u2013 Perspektiven geflu\u0308chteter Menschen auf die Warteschleife Asyl\u201c<\/a><\/li><li>Ausstellung zur Geografie des zugewiesenen Bereichs, in dem sich Fl\u00fcchtlinge bewegen: <a href=\"https:\/\/www.invisibleborders.de\/ausstellung.html\" target=\"_blank\" rel=\"noopener\">&#8222;Residenzpflicht \u2014 Invisible Borders&#8220;<\/a><\/li><li>Theaterst\u00fccke \u00fcber Menschen, die &#8222;Grenzen \u00fcberwunden haben&#8220;, mit dem Ziel, in Sicherheit und Menschenw\u00fcrde zu leben: <a href=\"http:\/\/buehne-fuer-menschenrechte.de\/\" target=\"_blank\" rel=\"noopener\">&#8222;B\u00fchne f\u00fcr Menschenrechte&#8220;<\/a><\/li><\/ul><h3>Begegnungsm\u00f6glichkeiten \/ Workshops<\/h3><p>Kontakt zu Asylsuchenden f\u00fcr Begegnungsprojekte erh\u00e4lt man am besten \u00fcber lokale Vereine. Diese organisieren auch oft Workshops zum Thema &#8222;Flucht, Migration, Asyl&#8220;. Ansprechpartner finden sich beispielsweise \u00fcber<\/p><ul><li>den <a href=\"https:\/\/www.fluechtlingsrat.de\/\" target=\"_blank\" rel=\"noopener\">Fl\u00fcchtlingsrat des jeweiligen Bundeslandes<\/a>,<\/li><li>das bundesweite <a href=\"https:\/\/www.netzwerk-courage.de\/\" target=\"_blank\" rel=\"noopener\">Netzwerk f\u00fcr Demokratie und Courage e.V.<\/a>,<\/li><li><a href=\"https:\/\/wie-kann-ich-helfen.info\/\" target=\"_blank\" rel=\"noopener\">lokale Initiativen<\/a>.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59dbbfb elementor-widget elementor-widget-text-editor\" data-id=\"59dbbfb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Bildnachweis<\/h2><ul><li><p>Bilder:\u00a0Herol\u00e9, <a href=\"https:\/\/www.shutterstock.com\/de\/\">Shutterstock\u00a0<\/a><\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fdc617 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fdc617\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46e54fa\" data-id=\"46e54fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Der Lernfokus \u201eFlucht, Asyl, Migration\u201c ist in den Lehrpl\u00e4nen nicht vorgeschrieben. Dennoch sehen sich viele Schulen und Lehrer angesichts der aktuellen gesellschaftlichen Debatten in der Verantwortung, das Thema auch im Unterricht mit den Sch\u00fclern zu besprechen. Daf\u00fcr eignen sich beispielsweise die F\u00e4cher Geschichte, Sozialkunde, Geographie oder der Deutschunterricht.<\/p>\n","protected":false},"author":6,"featured_media":2008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politisches"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Flucht und Asyl als Unterrichtsthema - Tipps<\/title>\n<meta name=\"description\" content=\"Wie kann das Thema &quot;Flucht, Asyl, Migration&quot; im Unterricht behandelt werden? Welche Methoden sind geeignet? Wir haben einige Ratschl\u00e4ge zusammengefasst.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flucht und Asyl als Unterrichtsthema - Tipps\" \/>\n<meta property=\"og:description\" content=\"Wie kann das Thema &quot;Flucht, Asyl, Migration&quot; im Unterricht behandelt werden? Welche Methoden sind geeignet? Wir haben einige Ratschl\u00e4ge zusammengefasst.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/\" \/>\n<meta property=\"og:site_name\" content=\"HEROL\u00c9 Ratgeber\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HeroleKlassenfahrten\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-08T10:40:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-04T09:10:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"579\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heike Philipp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@heike.bach\" \/>\n<meta name=\"twitter:site\" content=\"@herole_reisen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heike Philipp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/\"},\"author\":{\"name\":\"Heike Philipp\",\"@id\":\"https:\/\/www.herole.de\/blog\/#\/schema\/person\/13fb982c1909aaffcf2c09f0fde399ba\"},\"headline\":\"Flucht und Asyl als Unterrichtsthema &#8211; Tipps\",\"datePublished\":\"2016-03-08T10:40:14+00:00\",\"dateModified\":\"2024-10-04T09:10:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/\"},\"wordCount\":1555,\"publisher\":{\"@id\":\"https:\/\/www.herole.de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg\",\"articleSection\":[\"Politisches\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/\",\"url\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/\",\"name\":\"Flucht und Asyl als Unterrichtsthema - Tipps\",\"isPartOf\":{\"@id\":\"https:\/\/www.herole.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg\",\"datePublished\":\"2016-03-08T10:40:14+00:00\",\"dateModified\":\"2024-10-04T09:10:18+00:00\",\"description\":\"Wie kann das Thema \\\"Flucht, Asyl, Migration\\\" im Unterricht behandelt werden? Welche Methoden sind geeignet? Wir haben einige Ratschl\u00e4ge zusammengefasst.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#primaryimage\",\"url\":\"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg\",\"contentUrl\":\"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg\",\"width\":1000,\"height\":579,\"caption\":\"Wer schon in der Schule aktiv mitarbeitet, hat hinterher weniger Stress mit den Hausaufgaben!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.herole.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flucht und Asyl als Unterrichtsthema &#8211; Tipps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.herole.de\/blog\/#website\",\"url\":\"https:\/\/www.herole.de\/blog\/\",\"name\":\"HEROL\u00c9 Ratgeber\",\"description\":\"Wissenswertes rund um die Organisation von Klassenfahrten, zudem Lehrertipps und Themen des Schulalltags.\",\"publisher\":{\"@id\":\"https:\/\/www.herole.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.herole.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.herole.de\/blog\/#organization\",\"name\":\"HEROL\u00c9 Reisen GmbH\",\"url\":\"https:\/\/www.herole.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.herole.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/herole-logo.png\",\"contentUrl\":\"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/herole-logo.png\",\"width\":274,\"height\":70,\"caption\":\"HEROL\u00c9 Reisen GmbH\"},\"image\":{\"@id\":\"https:\/\/www.herole.de\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/HeroleKlassenfahrten\",\"https:\/\/x.com\/herole_reisen\",\"https:\/\/instagram.com\/heroleklassenfahrten\",\"https:\/\/www.youtube.com\/HeroleReisen\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.herole.de\/blog\/#\/schema\/person\/13fb982c1909aaffcf2c09f0fde399ba\",\"name\":\"Heike Philipp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.herole.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6010203aefccca33c04c1b210ceba8ee7e5a734d5844451cfadfb0913f869e7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6010203aefccca33c04c1b210ceba8ee7e5a734d5844451cfadfb0913f869e7a?s=96&d=mm&r=g\",\"caption\":\"Heike Philipp\"},\"sameAs\":[\"https:\/\/x.com\/heike.bach\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flucht und Asyl als Unterrichtsthema - Tipps","description":"Wie kann das Thema \"Flucht, Asyl, Migration\" im Unterricht behandelt werden? Welche Methoden sind geeignet? Wir haben einige Ratschl\u00e4ge zusammengefasst.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/","og_locale":"de_DE","og_type":"article","og_title":"Flucht und Asyl als Unterrichtsthema - Tipps","og_description":"Wie kann das Thema \"Flucht, Asyl, Migration\" im Unterricht behandelt werden? Welche Methoden sind geeignet? Wir haben einige Ratschl\u00e4ge zusammengefasst.\u00a0","og_url":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/","og_site_name":"HEROL\u00c9 Ratgeber","article_publisher":"https:\/\/www.facebook.com\/HeroleKlassenfahrten","article_published_time":"2016-03-08T10:40:14+00:00","article_modified_time":"2024-10-04T09:10:18+00:00","og_image":[{"width":1000,"height":579,"url":"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg","type":"image\/jpeg"}],"author":"Heike Philipp","twitter_card":"summary_large_image","twitter_creator":"@heike.bach","twitter_site":"@herole_reisen","twitter_misc":{"Verfasst von":"Heike Philipp","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#article","isPartOf":{"@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/"},"author":{"name":"Heike Philipp","@id":"https:\/\/www.herole.de\/blog\/#\/schema\/person\/13fb982c1909aaffcf2c09f0fde399ba"},"headline":"Flucht und Asyl als Unterrichtsthema &#8211; Tipps","datePublished":"2016-03-08T10:40:14+00:00","dateModified":"2024-10-04T09:10:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/"},"wordCount":1555,"publisher":{"@id":"https:\/\/www.herole.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#primaryimage"},"thumbnailUrl":"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg","articleSection":["Politisches"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/","url":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/","name":"Flucht und Asyl als Unterrichtsthema - Tipps","isPartOf":{"@id":"https:\/\/www.herole.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#primaryimage"},"image":{"@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#primaryimage"},"thumbnailUrl":"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg","datePublished":"2016-03-08T10:40:14+00:00","dateModified":"2024-10-04T09:10:18+00:00","description":"Wie kann das Thema \"Flucht, Asyl, Migration\" im Unterricht behandelt werden? Welche Methoden sind geeignet? Wir haben einige Ratschl\u00e4ge zusammengefasst.\u00a0","breadcrumb":{"@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#primaryimage","url":"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg","contentUrl":"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/blick-in-ein-klassenzimmer.jpg","width":1000,"height":579,"caption":"Wer schon in der Schule aktiv mitarbeitet, hat hinterher weniger Stress mit den Hausaufgaben!"},{"@type":"BreadcrumbList","@id":"https:\/\/www.herole.de\/blog\/unterrichtsthema-flucht-asyl-migration-praxis-tipps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.herole.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Flucht und Asyl als Unterrichtsthema &#8211; Tipps"}]},{"@type":"WebSite","@id":"https:\/\/www.herole.de\/blog\/#website","url":"https:\/\/www.herole.de\/blog\/","name":"HEROL\u00c9 Ratgeber","description":"Wissenswertes rund um die Organisation von Klassenfahrten, zudem Lehrertipps und Themen des Schulalltags.","publisher":{"@id":"https:\/\/www.herole.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.herole.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.herole.de\/blog\/#organization","name":"HEROL\u00c9 Reisen GmbH","url":"https:\/\/www.herole.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.herole.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/herole-logo.png","contentUrl":"https:\/\/www.herole.de\/blog\/wp-content\/uploads\/herole-logo.png","width":274,"height":70,"caption":"HEROL\u00c9 Reisen GmbH"},"image":{"@id":"https:\/\/www.herole.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HeroleKlassenfahrten","https:\/\/x.com\/herole_reisen","https:\/\/instagram.com\/heroleklassenfahrten","https:\/\/www.youtube.com\/HeroleReisen"]},{"@type":"Person","@id":"https:\/\/www.herole.de\/blog\/#\/schema\/person\/13fb982c1909aaffcf2c09f0fde399ba","name":"Heike Philipp","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.herole.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6010203aefccca33c04c1b210ceba8ee7e5a734d5844451cfadfb0913f869e7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6010203aefccca33c04c1b210ceba8ee7e5a734d5844451cfadfb0913f869e7a?s=96&d=mm&r=g","caption":"Heike Philipp"},"sameAs":["https:\/\/x.com\/heike.bach"]}]}},"_links":{"self":[{"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/posts\/2050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/comments?post=2050"}],"version-history":[{"count":0,"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/posts\/2050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/media\/2008"}],"wp:attachment":[{"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/media?parent=2050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/categories?post=2050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.herole.de\/blog\/wp-json\/wp\/v2\/tags?post=2050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}